{"id":56796,"date":"2024-04-03T14:59:22","date_gmt":"2024-04-03T18:59:22","guid":{"rendered":"https:\/\/www.cleo.on.ca\/?post_type=post&#038;p=56796"},"modified":"2024-04-03T14:59:22","modified_gmt":"2024-04-03T18:59:22","slug":"nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle","status":"publish","type":"post","link":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle","title":{"rendered":"Nouvel outil pour fixer une date \u00e0 la Cour criminelle"},"content":{"rendered":"<p>Justice pas-\u00e0-pas dispose d&rsquo;un <a href=\"https:\/\/stepstojustice.ca\/fr\/fixer-une-date-a-la-cour-criminelle\/\" target=\"_blank\" rel=\"noopener\">nouvel outil<\/a> pour aider les personnes qui se pr\u00e9sentent sans avocat(e) devant une Cour criminelle.<\/p>\n<p>Quand vous \u00eates accus\u00e9(e) d&rsquo;un crime, vous devez vous rendre r\u00e9guli\u00e8rement au tribunal pour tenir le juge au courant de votre affaire avant qu&rsquo;elle ne soit r\u00e9gl\u00e9e. Cet outil, en fonction de votre situation, vous aide \u00e0 d\u00e9cider du temps que vous pouvez demander avant votre prochaine date d&rsquo;audience. Il donne aussi une id\u00e9e de ce que vous pouvez dire au tribunal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Justice pas-\u00e0-pas dispose d&rsquo;un <a href=\"https:\/\/stepstojustice.ca\/fr\/fixer-une-date-a-la-cour-criminelle\/\" target=\"_blank\" rel=\"noopener\">nouvel outil<\/a> pour aider les personnes qui se pr\u00e9sentent sans avocat(e) devant une Cour criminelle.<br \/>\nQuand vous \u00eates accus\u00e9(e) d&rsquo;un crime, vous devez vous rendre r\u00e9guli\u00e8rement au tribunal pour tenir le juge au courant de votre affaire avant qu&rsquo;elle ne soit r\u00e9gl\u00e9e. Cet outil, en fonction de votre situation,<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1262],"tags":[],"class_list":["post-56796","post","type-post","status-publish","format-standard","hentry","category-dernieres-mises-a-jour"],"featured_image_src":null,"author_info":{"display_name":"Mira Poliszczuk","author_link":"https:\/\/www.cleo.on.ca\/fr\/author\/mira"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvel outil pour fixer une date \u00e0 la Cour criminelle - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvel outil pour fixer une date \u00e0 la Cour criminelle - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\" \/>\n<meta property=\"og:description\" content=\"Justice pas-\u00e0-pas dispose d&rsquo;un nouvel outil pour aider les personnes qui se pr\u00e9sentent sans avocat(e) devant une Cour criminelle. Quand vous \u00eates accus\u00e9(e) d&rsquo;un crime, vous devez vous rendre r\u00e9guli\u00e8rement au tribunal pour tenir le juge au courant de votre affaire avant qu&rsquo;elle ne soit r\u00e9gl\u00e9e. Cet outil, en fonction de votre situation,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle\" \/>\n<meta property=\"og:site_name\" content=\"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-03T18:59:22+00:00\" \/>\n<meta name=\"author\" content=\"Mira Poliszczuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TurnbullCo\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mira Poliszczuk\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle\"},\"author\":{\"name\":\"Mira Poliszczuk\",\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr#\\\/schema\\\/person\\\/c8adf9159092121590225b2077326c9f\"},\"headline\":\"Nouvel outil pour fixer une date \u00e0 la Cour criminelle\",\"datePublished\":\"2024-04-03T18:59:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle\"},\"wordCount\":99,\"articleSection\":[\"Actualit\u00e9s et mises \u00e0 jour\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle\",\"url\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle\",\"name\":\"Nouvel outil pour fixer une date \u00e0 la Cour criminelle - CLEO (Community Legal Education Ontario \\\/ \u00c9ducation juridique communautaire Ontario)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr#website\"},\"datePublished\":\"2024-04-03T18:59:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr#\\\/schema\\\/person\\\/c8adf9159092121590225b2077326c9f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\\\/nouveautes\\\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvel outil pour fixer une date \u00e0 la Cour criminelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr#website\",\"url\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr\",\"name\":\"CLEO (Community Legal Education Ontario \\\/ \u00c9ducation juridique communautaire Ontario)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cleo.on.ca\\\/fr#\\\/schema\\\/person\\\/c8adf9159092121590225b2077326c9f\",\"name\":\"Mira Poliszczuk\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/TurnbullCo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvel outil pour fixer une date \u00e0 la Cour criminelle - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle","og_locale":"fr_FR","og_type":"article","og_title":"Nouvel outil pour fixer une date \u00e0 la Cour criminelle - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","og_description":"Justice pas-\u00e0-pas dispose d&rsquo;un nouvel outil pour aider les personnes qui se pr\u00e9sentent sans avocat(e) devant une Cour criminelle. Quand vous \u00eates accus\u00e9(e) d&rsquo;un crime, vous devez vous rendre r\u00e9guli\u00e8rement au tribunal pour tenir le juge au courant de votre affaire avant qu&rsquo;elle ne soit r\u00e9gl\u00e9e. Cet outil, en fonction de votre situation,","og_url":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle","og_site_name":"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","article_published_time":"2024-04-03T18:59:22+00:00","author":"Mira Poliszczuk","twitter_card":"summary_large_image","twitter_creator":"@TurnbullCo","twitter_misc":{"\u00c9crit par":"Mira Poliszczuk"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle#article","isPartOf":{"@id":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle"},"author":{"name":"Mira Poliszczuk","@id":"https:\/\/www.cleo.on.ca\/fr#\/schema\/person\/c8adf9159092121590225b2077326c9f"},"headline":"Nouvel outil pour fixer une date \u00e0 la Cour criminelle","datePublished":"2024-04-03T18:59:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle"},"wordCount":99,"articleSection":["Actualit\u00e9s et mises \u00e0 jour"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle","url":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle","name":"Nouvel outil pour fixer une date \u00e0 la Cour criminelle - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","isPartOf":{"@id":"https:\/\/www.cleo.on.ca\/fr#website"},"datePublished":"2024-04-03T18:59:22+00:00","author":{"@id":"https:\/\/www.cleo.on.ca\/fr#\/schema\/person\/c8adf9159092121590225b2077326c9f"},"breadcrumb":{"@id":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cleo.on.ca\/fr\/nouveautes\/nouvel-outil-pour-fixer-une-date-a-la-cour-criminelle#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cleo.on.ca\/fr"},{"@type":"ListItem","position":2,"name":"Nouvel outil pour fixer une date \u00e0 la Cour criminelle"}]},{"@type":"WebSite","@id":"https:\/\/www.cleo.on.ca\/fr#website","url":"https:\/\/www.cleo.on.ca\/fr","name":"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cleo.on.ca\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.cleo.on.ca\/fr#\/schema\/person\/c8adf9159092121590225b2077326c9f","name":"Mira Poliszczuk","sameAs":["https:\/\/x.com\/TurnbullCo"]}]}},"meta_box":{"blog_image_type":"image-big","external_url":"","do_not_show_on_homepage":"0"},"_links":{"self":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/post\/56796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/post"}],"about":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/comments?post=56796"}],"version-history":[{"count":1,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/post\/56796\/revisions"}],"predecessor-version":[{"id":56797,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/post\/56796\/revisions\/56797"}],"wp:attachment":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=56796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/categories?post=56796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/tags?post=56796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}