{"id":47609,"date":"2012-05-11T20:00:37","date_gmt":"2012-05-12T00:00:37","guid":{"rendered":""},"modified":"2020-09-24T19:44:02","modified_gmt":"2020-09-24T19:44:02","slug":"que-faire-si-la-police-me-demande-qui-je-suis","status":"publish","type":"publications-page","link":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis","title":{"rendered":"Que faire si la police me demande qui je suis?"},"content":{"rendered":"<h2>Si des policiers envisagent votre arrestation<\/h2>\n<p>Si des policiers envisagent votre arrestation, ils voudront conna\u00eetre votre identit\u00e9. Voici diff\u00e9rentes raisons pour lesquelles vous pourriez vouloir leur dire qui vous \u00eates :<\/p>\n<ul>\n<li>Si la police recherche quelqu&rsquo;un d&rsquo;autre, vous pourriez \u00e9viter une arrestation en d\u00e9montrant que vous n&rsquo;\u00eates pas la personne recherch\u00e9e.<\/li>\n<li>Si la police croit que vous avez pu commettre une infraction et que vous refusez de dire qui vous \u00eates, vous risquez d&rsquo;\u00eatre arr\u00eat\u00e9(e) et d\u00e9tenu(e) \u00e0 un poste de police jusqu&rsquo;\u00e0 ce que la police \u00e9tablisse votre identit\u00e9 ou jusqu&rsquo;\u00e0 ce qu&rsquo;elle soit tenue de vous amener devant le tribunal pour une audience sur le cautionnement.<\/li>\n<li>Si la police croit que vous avez commis une infraction mineure et que vous lui dites qui vous \u00eates, la police pourrait vous \u00e9pargner l&rsquo;arrestation et se contenter de vous remettre un document vous indiquant quand vous devez vous pr\u00e9senter devant le tribunal.<\/li>\n<\/ul>\n<p>Si vous donnez un faux nom ou une fausse adresse, vous pouvez \u00eatre accus\u00e9(e) d&rsquo;entrave \u00e0 la justice ou \u00e0 l&rsquo;action d&rsquo;un agent de police.<\/p>\n<h2>Si des policiers effectuent une collecte de renseignements identificatoires ou un contr\u00f4le de routine<\/h2>\n<p>Il y a &laquo; collecte de renseignements identificatoires &raquo; lorsque la police vous intercepte et vous demande de r\u00e9v\u00e9ler votre identit\u00e9. La police peut proc\u00e9der \u00e0 cette collecte, m\u00eame si elle n&rsquo;a aucun motif de soup\u00e7onner que vous avez commis un acte criminel ou que vous avez quelque renseignement que ce soit au sujet d&rsquo;un acte criminel. Cette proc\u00e9dure est parfois appel\u00e9e un &laquo; contr\u00f4le de routine &raquo;.<\/p>\n<p>Les r\u00e8gles sur la collecte de renseignements identificatoires et le contr\u00f4le de routine s&rsquo;appliquent lorsque la police :<\/p>\n<ul>\n<li>m\u00e8ne une enqu\u00eate sur de possibles infractions ou des activit\u00e9s suspectes<\/li>\n<li>recueille des renseignements pouvant l&rsquo;aider \u00e0 effectuer son travail<\/li>\n<\/ul>\n<h2>Restrictions concernant le profilage racial<\/h2>\n<p>De fa\u00e7on g\u00e9n\u00e9rale, les agents de police n&rsquo;ont pas le droit de vous demander qui vous \u00eates si leur demande d\u00e9coule en partie du seul fait que, \u00e0 leurs yeux, vous appartenez \u00e0 une communaut\u00e9 racialis\u00e9e particuli\u00e8re. Cette r\u00e8gle s&rsquo;applique m\u00eame si les agents recherchent une personne qui appartient au m\u00eame groupe racial ou groupe d&rsquo;\u00e2ge que vous ou est du m\u00eame sexe que vous.<\/p>\n<p>Cela dit, si les agents ont d&rsquo;autres motifs de croire que vous \u00eates peut-\u00eatre la personne qu&rsquo;ils recherchent, ils pourront \u00eatre en mesure de vous demander qui vous \u00eates. Voici quelques exemples de tels motifs :<\/p>\n<ul>\n<li>votre apparence, y compris votre taille et votre poids, la couleur de vos cheveux et de vos yeux, ou ce que vous portez<\/li>\n<li>l&rsquo;endroit o\u00f9 les agents vous interceptent \u2014 leur demande ne doit toutefois pas partir du seul fait qu&rsquo;il s&rsquo;agit d&rsquo;un lieu o\u00f9 de nombreux crimes sont commis<\/li>\n<li>le type d&rsquo;automobile dans laquelle vous vous trouvez<\/li>\n<li>les personnes avec lesquelles vous vous trouvez<\/li>\n<li>ce que vous \u00eates en train de faire<\/li>\n<\/ul>\n<p>Si vous refusez de r\u00e9pondre ou de parler aux policiers et que vous avez le droit de leur opposer un tel refus, ils ne peuvent utiliser ce refus comme motif pour vous demander qui vous \u00eates.<\/p>\n<h2>Ce que l&rsquo;agent de police doit faire durant un contr\u00f4le de routine<\/h2>\n<p>Lorsque, dans le cadre d&rsquo;un contr\u00f4le de routine, un agent de police vous demande qui vous \u00eates, il doit vous informer, <strong>\u00e0 la fois<\/strong> :<\/p>\n<ul>\n<li>de votre droit de ne pas lui r\u00e9pondre<\/li>\n<li>du motif pour lequel il vous fait cette demande<\/li>\n<\/ul>\n<p>Cela dit, l&rsquo;agent de police n&rsquo;est pas tenu de vous communiquer l&rsquo;information qui pr\u00e9c\u00e8de s&rsquo;il consid\u00e8re qu&rsquo;une telle communication pourrait compromettre la s\u00e9curit\u00e9 d&rsquo;une certaine personne.<\/p>\n<p>L&rsquo;agent de police n&rsquo;est pas non plus tenu de vous informer du motif de sa demande si une telle communication risque de r\u00e9v\u00e9ler l&rsquo;identit\u00e9 d&rsquo;une personne qui doit \u00eatre prot\u00e9g\u00e9e ou si une enqu\u00eate polici\u00e8re risque vraisemblablement de s&rsquo;en trouver compromise.<\/p>\n<p>L&rsquo;agent de police doit vous remettre un document qui comprend les renseignements suivants :<\/p>\n<ul>\n<li>son nom et son num\u00e9ro d&rsquo;insigne<\/li>\n<li>la fa\u00e7on de communiquer avec le Bureau du directeur ind\u00e9pendant de l&rsquo;examen de la police pour porter plainte contre la police<\/li>\n<li>la personne \u00e0 contacter pour savoir quels renseignements la police d\u00e9tient \u00e0 votre sujet<\/li>\n<\/ul>\n<p>L&rsquo;agent de police doit vous remettre ce document que vous lui donniez des renseignements sur vous ou non.<\/p>\n<p><p>Si vous songez \u00e0 porter plainte contre des agents de police, demandez des conseils juridiques. Pour savoir o\u00f9 obtenir une assistance juridique, rendez-vous \u00e0 la section <a href=\"https:\/\/www.cleo.on.ca\/fr\/publications\/fpolstop\/comment-obtenir-une-assistance-juridique\" target=_blank\">Comment obtenir une assistance juridique?<\/a><\/p>\n<p>Les r\u00e8gles relatives au contr\u00f4le de routine ne s&rsquo;appliquent pas dans les circonstances suivantes :<\/p>\n<ul>\n<li>la police a des motifs raisonnables de croire qu&rsquo;une infraction a \u00e9t\u00e9 commise ou sera commise<\/li>\n<li>vous \u00eates en \u00e9tat d&rsquo;arrestation ou vous \u00eates d\u00e9tenu(e)<\/li>\n<li>une autre disposition l\u00e9gislative \u00e9nonce que vous devez r\u00e9v\u00e9ler votre identit\u00e9<\/li>\n<li>l&rsquo;agent de police ex\u00e9cute un mandat ou agit conform\u00e9ment \u00e0 une ordonnance judiciaire<\/li>\n<li>l&rsquo;agent de police participe \u00e0 une op\u00e9ration d&rsquo;infiltration au moment o\u00f9 il vous parle<\/li>\n<\/ul>\n<h2>Si vous \u00eates \u00e0 bicyclette<\/h2>\n<p>Si vous \u00eates \u00e0 bicyclette, la police peut vous intercepter si elle croit que vous avez contrevenu \u00e0 la l\u00e9gislation provinciale ou \u00e0 la r\u00e9glementation municipale sur la circulation routi\u00e8re. Dans un tel cas, vous devez vous arr\u00eater et lui donner votre nom et votre adresse. Si vous refusez, les policiers peuvent vous arr\u00eater.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-47609","publications-page","type-publications-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Que faire si la police me demande qui je suis? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que faire si la police me demande qui je suis? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\" \/>\n<meta property=\"og:description\" content=\"Si des policiers envisagent votre arrestation Si des policiers envisagent votre arrestation, ils voudront conna\u00eetre votre identit\u00e9. Voici diff\u00e9rentes raisons pour lesquelles vous pourriez vouloir leur dire qui vous \u00eates : Si la police recherche quelqu&rsquo;un d&rsquo;autre, vous pourriez \u00e9viter une arrestation en d\u00e9montrant que vous n&rsquo;\u00eates pas la personne recherch\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis\" \/>\n<meta property=\"og:site_name\" content=\"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-24T19:44:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis\",\"url\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis\",\"name\":\"Que faire si la police me demande qui je suis? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\",\"isPartOf\":{\"@id\":\"https:\/\/www.cleo.on.ca\/fr#website\"},\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"dateModified\":\"2020-09-24T19:44:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cleo.on.ca\/fr\/accueil-2\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publication pages\",\"item\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Que faire si la police me demande qui je suis?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cleo.on.ca\/fr#website\",\"url\":\"https:\/\/www.cleo.on.ca\/fr\",\"name\":\"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cleo.on.ca\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que faire si la police me demande qui je suis? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis","og_locale":"fr_FR","og_type":"article","og_title":"Que faire si la police me demande qui je suis? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","og_description":"Si des policiers envisagent votre arrestation Si des policiers envisagent votre arrestation, ils voudront conna\u00eetre votre identit\u00e9. Voici diff\u00e9rentes raisons pour lesquelles vous pourriez vouloir leur dire qui vous \u00eates : Si la police recherche quelqu&rsquo;un d&rsquo;autre, vous pourriez \u00e9viter une arrestation en d\u00e9montrant que vous n&rsquo;\u00eates pas la personne recherch\u00e9e.","og_url":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis","og_site_name":"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","article_modified_time":"2020-09-24T19:44:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis","url":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis","name":"Que faire si la police me demande qui je suis? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","isPartOf":{"@id":"https:\/\/www.cleo.on.ca\/fr#website"},"datePublished":"-0001-11-30T00:00:00+00:00","dateModified":"2020-09-24T19:44:02+00:00","breadcrumb":{"@id":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/que-faire-si-la-police-me-demande-qui-je-suis#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cleo.on.ca\/fr\/accueil-2"},{"@type":"ListItem","position":2,"name":"Publication pages","item":"https:\/\/www.cleo.on.ca\/fr\/publications-page"},{"@type":"ListItem","position":3,"name":"Que faire si la police me demande qui je suis?"}]},{"@type":"WebSite","@id":"https:\/\/www.cleo.on.ca\/fr#website","url":"https:\/\/www.cleo.on.ca\/fr","name":"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cleo.on.ca\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/publications-page\/47609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/publications-page"}],"about":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/types\/publications-page"}],"version-history":[{"count":0,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/publications-page\/47609\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=47609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}