{"id":47663,"date":"2012-05-14T18:32:31","date_gmt":"2012-05-14T22:32:31","guid":{"rendered":""},"modified":"2024-08-09T14:00:52","modified_gmt":"2024-08-09T18:00:52","slug":"qui-sadresser-pour-de-laide-et-de-linformation","status":"publish","type":"publications-page","link":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation","title":{"rendered":"\u00c0 qui s&rsquo;adresser pour de l&rsquo;aide et de l&rsquo;information?"},"content":{"rendered":"<h3><span lang=\"fr\">\u00c9ducation juridique communautaire Ontario (CLEO)\u00a0<\/span><\/h3>\n<p><span lang=\"fr\">CLEO propose une s\u00e9rie de ressources sur la maltraitance et la violence familiale disponibles en ligne et en version imprim\u00e9e. Les th\u00e9matiques de ladite s\u00e9rie incluent la violence familiale, la maltraitance des personnes \u00e2g\u00e9es et la maltraitance des personnes handicap\u00e9es. Pour commander ces publications ou les consulter en ligne, cliquez sur\u00a0<a href=\"http:\/\/www.cleo.on.ca\/fr\/resources-and-publications\/droit-de-la-famille\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-safelink=\"true\" data-linkindex=\"0\">www.cleo.on.ca\/fr\/resources-and-publications\/droit-de-la-famille<\/a> ou composez le <strong>416-408-4420<\/strong>.\u00a0<\/span><\/p>\n<p><span lang=\"fr\">Justice pas-\u00e0-pas de CLEO est un site web qui fournit des renseignements d\u00e9taill\u00e9s sur les probl\u00e8mes juridiques courants, y compris la maltraitance des personnes \u00e2g\u00e9es. Justice pas-\u00e0-pas propose des outils pratiques tels que des plans de s\u00e9curit\u00e9 et des listes de contr\u00f4le, ainsi que des informations d\u2019aiguillage vers les services juridiques et sociaux. Cliquez sur\u00a0<a href=\"http:\/\/www.justicepasapas.ca\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-safelink=\"true\" data-linkindex=\"1\">www.justicepasapas.ca<\/a>.\u00a0<\/span><\/p>\n<p><span lang=\"fr\">Le Parcours guid\u00e9 de CLEO pour agir face \u00e0 la maltraitance des personnes \u00e2g\u00e9es est un questionnaire en ligne qui vous donne des informations et des ressources pour vous aider \u00e0 intervenir face \u00e0 la maltraitance des personnes \u00e2g\u00e9es. Le Parcours vous pose des questions et utilise vos r\u00e9ponses pour trouver des informations et cr\u00e9er un plan de s\u00e9curit\u00e9 et une liste de contr\u00f4le personnalis\u00e9e. Le Parcours est gratuit. <a href=\"http:\/\/www.stepstojustice.ca\/fr\/parcours-guides-accueil\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-safelink=\"true\" data-linkindex=\"2\">www.stepstojustice.ca\/fr\/parcours-guides-accueil\/<\/a>.\u00a0<\/span><\/p>\n<h3>Pour des services juridiques<\/h3>\n<p>Communiquez avec <strong>Advocacy Centre for the Elderly (ACE)<\/strong>.<\/p>\n<p class=\"indent\">T\u00e9l\u00e9phone : <strong>416-598-2656<\/strong><\/p>\n<p class=\"indent\">Sans frais : <strong>1-855-598-2656<\/strong><\/p>\n<p class=\"indent\">T\u00e9l\u00e9copieur : <strong>416-598-7924<\/strong><\/p>\n<p class=\"indent\">Site web : <a href=\"http:\/\/www.acelaw.ca\/\" target=\"_blank\" rel=\"noopener\">www.acelaw.ca<\/a><\/p>\n<p>Pour trouver la <strong>clinique juridique communautaire<\/strong> la plus pr\u00e8s de chez vous, rendez-vous au site web d&rsquo;Aide juridique Ontario \u00e0 l&rsquo;adresse <a href=\"http:\/\/www.legalaid.on.ca\/fr\/\" target=\"_blank\" rel=\"noopener\">www.legalaid.on.ca\/fr<\/a>.<\/p>\n<p>Vous pouvez aussi t\u00e9l\u00e9phoner \u00e0 Aide juridique Ontario :<\/p>\n<p class=\"indent\">Sans frais : <strong>1-800-668-8258<\/strong><\/p>\n<p class=\"indent\">ATS, service de relais Bell : <strong>1-800-855-0511<\/strong><\/p>\n<h3>Pour obtenir des services ou pour plus d&rsquo;information<\/h3>\n<p>Communiquez avec <strong>Maltraitance des personnes \u00e2g\u00e9es Ontario<\/strong>.<\/p>\n<p class=\"indent\">T\u00e9l\u00e9phone : <strong>416-916-6728<\/strong><\/p>\n<p class=\"indent\">Site web : <a href=\"http:\/\/www.elderabuseontario.com\/french\/\" target=\"_blank\" rel=\"noopener\">www.elderabuseontario.com\/french<\/a><\/p>\n<h3>Pour de l&rsquo;information sur les programmes gouvernementaux et sur les services offerts<\/h3>\n<p>Composez le <strong>211<\/strong>.<\/p>\n<p>Communiquez avec <strong>ServiceOntario<\/strong>.<\/p>\n<p class=\"indent\">Sans frais : <strong>1-800-267-8097<\/strong><\/p>\n<p class=\"indent\">Toll-free TTY : <strong>1-800-268-7095<\/strong><\/p>\n<p class=\"indent\">Site web : <a href=\"https:\/\/www.ontario.ca\/welcome-serviceontario\" target=\"_blank\" rel=\"noopener\">www.serviceontario.ca<\/a><\/p>\n<h3>Pour conna\u00eetre les coordonn\u00e9es du R\u00e9seau local d&rsquo;int\u00e9gration des services de sant\u00e9 (RLISS) de votre localit\u00e9<\/h3>\n<p>Composez le <strong>211<\/strong> ou visitez l&rsquo;adresse <a href=\"http:\/\/healthcareathome.ca\/\" target=\"_blank\" rel=\"noopener\">www.healthcareathome.ca<\/a>.<\/p>\n<h3>Pour signaler des mauvais traitements inflig\u00e9s dans une maison de retraite<\/h3>\n<p>T\u00e9l\u00e9phonez \u00e0 l&rsquo;Office de r\u00e9glementation des maisons de retraite au <strong>1-855-275-7472<\/strong>.<\/p>\n<h3>Pour signaler des mauvais traitements inflig\u00e9s dans un foyer de soins de longue dur\u00e9e<\/h3>\n<p>Communiquez avec la <strong>Ligne ACTION du minist\u00e8re de la Sant\u00e9 et des Soins de longue dur\u00e9e<\/strong>.<\/p>\n<p class=\"indent\">Sans frais : <strong>1-866-434-0144<\/strong><\/p>\n<p class=\"indent\">ATS sans frais : <strong>1-800-387-5559<\/strong><\/p>\n<p>Vous pouvez aussi appeler la Ligne ACTION pour faire part de vos probl\u00e8mes, pr\u00e9occupations ou plaintes concernant des soins \u00e0 domicile, un foyer de soins de longue dur\u00e9e ou un RLISS.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-47663","publications-page","type-publications-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c0 qui s&#039;adresser pour de l&#039;aide et de l&#039;information? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 qui s&#039;adresser pour de l&#039;aide et de l&#039;information? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\" \/>\n<meta property=\"og:description\" content=\"\u00c9ducation juridique communautaire Ontario (CLEO)\u00a0 CLEO propose une s\u00e9rie de ressources sur la maltraitance et la violence familiale disponibles en ligne et en version imprim\u00e9e. Les th\u00e9matiques de ladite s\u00e9rie incluent la violence familiale, la maltraitance des personnes \u00e2g\u00e9es et la maltraitance des personnes handicap\u00e9es. Pour commander ces publications ou les consulter en ligne,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation\" \/>\n<meta property=\"og:site_name\" content=\"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-09T18:00:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation\",\"url\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation\",\"name\":\"\u00c0 qui s'adresser pour de l'aide et de l'information? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\",\"isPartOf\":{\"@id\":\"https:\/\/www.cleo.on.ca\/fr#website\"},\"datePublished\":\"2012-05-14T22:32:31+00:00\",\"dateModified\":\"2024-08-09T18:00:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cleo.on.ca\/fr\/accueil-2\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publication pages\",\"item\":\"https:\/\/www.cleo.on.ca\/fr\/publications-page\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c0 qui s&#8217;adresser pour de l&#8217;aide et de l&#8217;information?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cleo.on.ca\/fr#website\",\"url\":\"https:\/\/www.cleo.on.ca\/fr\",\"name\":\"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cleo.on.ca\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 qui s'adresser pour de l'aide et de l'information? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 qui s'adresser pour de l'aide et de l'information? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","og_description":"\u00c9ducation juridique communautaire Ontario (CLEO)\u00a0 CLEO propose une s\u00e9rie de ressources sur la maltraitance et la violence familiale disponibles en ligne et en version imprim\u00e9e. Les th\u00e9matiques de ladite s\u00e9rie incluent la violence familiale, la maltraitance des personnes \u00e2g\u00e9es et la maltraitance des personnes handicap\u00e9es. Pour commander ces publications ou les consulter en ligne,","og_url":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation","og_site_name":"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","article_modified_time":"2024-08-09T18:00:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation","url":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation","name":"\u00c0 qui s'adresser pour de l'aide et de l'information? - CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","isPartOf":{"@id":"https:\/\/www.cleo.on.ca\/fr#website"},"datePublished":"2012-05-14T22:32:31+00:00","dateModified":"2024-08-09T18:00:52+00:00","breadcrumb":{"@id":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cleo.on.ca\/fr\/publications-page\/qui-sadresser-pour-de-laide-et-de-linformation#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cleo.on.ca\/fr\/accueil-2"},{"@type":"ListItem","position":2,"name":"Publication pages","item":"https:\/\/www.cleo.on.ca\/fr\/publications-page"},{"@type":"ListItem","position":3,"name":"\u00c0 qui s&#8217;adresser pour de l&#8217;aide et de l&#8217;information?"}]},{"@type":"WebSite","@id":"https:\/\/www.cleo.on.ca\/fr#website","url":"https:\/\/www.cleo.on.ca\/fr","name":"CLEO (Community Legal Education Ontario \/ \u00c9ducation juridique communautaire Ontario)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cleo.on.ca\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/publications-page\/47663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/publications-page"}],"about":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/types\/publications-page"}],"version-history":[{"count":1,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/publications-page\/47663\/revisions"}],"predecessor-version":[{"id":51165,"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/publications-page\/47663\/revisions\/51165"}],"wp:attachment":[{"href":"https:\/\/www.cleo.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=47663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}